{"id":24209,"date":"2024-06-14T09:23:39","date_gmt":"2024-06-14T07:23:39","guid":{"rendered":"https:\/\/varendcorso.nl\/boten\/13-corsoboot-de-lier\/"},"modified":"2026-06-19T15:36:40","modified_gmt":"2026-06-19T13:36:40","slug":"13-corsoboot-de-lier","status":"publish","type":"boten","link":"https:\/\/varendcorso.nl\/de\/boten\/13-corsoboot-de-lier\/","title":{"rendered":"13. Corsoboot De Lier"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li>Eigent\u00fcmer: Paul van Koppen und Jack Groenewegen<\/li>\n\n\n\n<li>Titel: Die magischen Blumen<\/li>\n\n\n\n<li>Arrangement: Team De Lier<\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p class=\"wp-block-paragraph\">Willkommen in der zauberhaften Welt von \u201eDe Magische Bloemen\u201c.<\/p>\n\n<p class=\"wp-block-paragraph\">Vor Ihnen gleitet das Festumzugsboot von De Lier dahin: ein zauberhaftes Blumenfeld voller seltener Blumen und besonderer Pflanzen, von denen jede ihre eigene heilende Kraft besitzt. Inmitten dieser farbenfrohen Blumenwelt k\u00fcmmern sich geheimnisvolle magische Wesen mit Liebe und Sorgfalt um alles, was w\u00e4chst und bl\u00fcht. <\/p>\n\n<p class=\"wp-block-paragraph\">Um dieses schwimmende Blumenfeld zum Leben zu erwecken, wurden nicht weniger als Hunderte von Blumen und Pflanzen in das Boot integriert. Hinter dem, was Sie hier sehen, stecken monatelange Vorbereitungen. Unser Team aus Freiwilligen hat mit viel Leidenschaft daran gearbeitet, Design, Technik, Gestaltung und Inszenierung miteinander zu verbinden. Alles, um eine Fantasiewelt zu erschaffen, die vom Wasser aus immer wieder \u00fcberrascht.   <\/p>\n\n<p class=\"wp-block-paragraph\">Und nat\u00fcrlich darf dabei das typische Engagement der Einwohner von Lier nicht fehlen. Mit Kreativit\u00e4t, Zusammenarbeit und Geselligkeit haben wir ein Festwagenboot geschaffen, in dem Fantasie und handwerkliches K\u00f6nnen vereint sind. <\/p>\n\n<p class=\"wp-block-paragraph\">Im Namen von Corsoboot De Lier w\u00fcnschen wir Ihnen einen zauberhaften Tag und hoffen, dass Sie diese farbenfrohe Reise durch unsere Blumenwelt genie\u00dfen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Willkommen in der zauberhaften Welt von \u201eDe Magische Bloemen\u201c. Vor Ihnen gleitet das Festumzugsboot von De Lier dahin: ein zauberhaftes Blumenfeld voller seltener Blumen und besonderer Pflanzen, von denen jede ihre eigene heilende Kraft besitzt. Inmitten dieser farbenfrohen Blumenwelt k\u00fcmmern sich geheimnisvolle magische Wesen mit Liebe und Sorgfalt um alles, was w\u00e4chst und bl\u00fcht. Um [&hellip;]<\/p>\n","protected":false},"featured_media":24560,"template":"","boten-category":[65],"class_list":["post-24209","boten","type-boten","status-publish","has-post-thumbnail","hentry","boten-category-65"],"_links":{"self":[{"href":"https:\/\/varendcorso.nl\/de\/wp-json\/wp\/v2\/boten\/24209","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/varendcorso.nl\/de\/wp-json\/wp\/v2\/boten"}],"about":[{"href":"https:\/\/varendcorso.nl\/de\/wp-json\/wp\/v2\/types\/boten"}],"version-history":[{"count":0,"href":"https:\/\/varendcorso.nl\/de\/wp-json\/wp\/v2\/boten\/24209\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/varendcorso.nl\/de\/wp-json\/wp\/v2\/media\/24560"}],"wp:attachment":[{"href":"https:\/\/varendcorso.nl\/de\/wp-json\/wp\/v2\/media?parent=24209"}],"wp:term":[{"taxonomy":"boten-category","embeddable":true,"href":"https:\/\/varendcorso.nl\/de\/wp-json\/wp\/v2\/boten-category?post=24209"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}